{"id":17023,"date":"2022-09-26T10:37:09","date_gmt":"2022-09-26T08:37:09","guid":{"rendered":"https:\/\/www.imergroup.com\/annuncio\/candidatura-spontanea\/"},"modified":"2026-02-02T17:33:31","modified_gmt":"2026-02-02T16:33:31","slug":"initiativbewerbung","status":"publish","type":"announcement","link":"https:\/\/www.imergroup.com\/de\/annuncio\/initiativbewerbung\/","title":{"rendered":"INITIATIVBEWERBUNG"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Wenn Sie Teil unserer Gruppe werden m\u00f6chten, geben Sie Ihre Daten in die Felder des untenstehenden Formulars ein, w\u00e4hlen Sie den f\u00fcr Sie interessanten Fachbereich aus und senden Sie Ihren Lebenslauf ab.<\/p>\n<p>Wenn Sie ein frischgebackener Hochschulabsolvent bzw. Schulabg\u00e4nger sind und Ihre erste berufliche Chance suchen, geben Sie bitte den f\u00fcr Sie interessanten Praktikumsbereich an.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-17023","announcement","type-announcement","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.imergroup.com\/de\/wp-json\/wp\/v2\/announcement\/17023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imergroup.com\/de\/wp-json\/wp\/v2\/announcement"}],"about":[{"href":"https:\/\/www.imergroup.com\/de\/wp-json\/wp\/v2\/types\/announcement"}],"wp:attachment":[{"href":"https:\/\/www.imergroup.com\/de\/wp-json\/wp\/v2\/media?parent=17023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}